{"id":5948,"date":"2023-03-10T10:52:10","date_gmt":"2023-03-10T10:52:10","guid":{"rendered":"https:\/\/www.sergioparis.it\/?p=5948"},"modified":"2023-06-13T16:52:32","modified_gmt":"2023-06-13T16:52:32","slug":"traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu","status":"publish","type":"post","link":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/","title":{"rendered":"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9"},"content":{"rendered":"\n<p>L\u2019intelligenza artificiale sta rivoluzionando il mondo del lavoro e non in ultimo anche le professioni intellettuali, quelle in cui il cervello umano si esprime al meglio, si sentono minacciate dagli enormi passi in avanti che questa nuova frontiera dell\u2019innovazione tecnologica sta compiendo.<\/p>\n\n\n\n<p>Oggi si parla molto della nuova applicazione Chat GPT. Vediamo in sintesi di cosa si tratta e perch\u00e9 lo sviluppo di questa nuova tecnologia pu\u00f2 minacciare la figura del traduttore.<\/p>\n\n\n\n<p>Chat GPT&nbsp;\u00e8 il nuovo modello sviluppato da Open AI e fa parte dei&nbsp;modelli GPT-3&nbsp;(Generative Pre-trained Transformer 3). Sono modelli di intelligenza artificiale basati sul&nbsp;machine learning&nbsp;non supervisionato. Funzionano utilizzando una tecnica di&nbsp;deep learning&nbsp;nota come&nbsp;transformer, che consiste nell\u2019utilizzare una&nbsp;rete neurale&nbsp;per analizzare e comprendere il significato di un testo.<\/p>\n\n\n\n<p>Chat GPT&nbsp;nello specifico fa parte della famiglia degli&nbsp;Instruct GPT,&nbsp;quindi&nbsp;modelli&nbsp;formati tramite deep learning ma poi ottimizzati tramite il&nbsp;rinforzo umano, ovvero una tecnica nota come&nbsp;RLHF&nbsp;\u2013 Reinforcement Learning From&nbsp;Human&nbsp;Feedback.<\/p>\n\n\n\n<p>Chat GPT&nbsp;\u00e8 stato realizzato e reso pubblico a novembre del 2022. Grazie alla sua potenza e alla sua facilit\u00e0 d\u2019utilizzo sta spopolando sul web e molti, vista anche la possibilit\u00e0 di accedervi&nbsp;gratuitamente, ne stanno scoprendo le potenzialit\u00e0<a id=\"_ftnref1\" href=\"#_ftn1\">[1]<\/a>.<\/p>\n\n\n\n<p>Chat GPT rende l\u2019interazione con l\u2019intelligenza artificiale pi\u00f9 naturale e intuitiva. Realizzato per ottimizzare la conversazione e facilitare l\u2019utilizzo da parte degli utenti,&nbsp;Chat GPT&nbsp;\u00e8 stato creato per aiutare gli utenti a interagire in modo pi\u00f9 semplice e fluido con&nbsp;<a href=\"https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/\">GPT-3.<\/a>&nbsp;Con&nbsp;Chat GPT&nbsp;\u00e8 possibile accedere gratuitamente, basta iscriversi con il proprio account Google o Microsoft.&nbsp;<\/p>\n\n\n\n<p>In sintesi, possiamo chiedere a Chat GPT di redigere un testo, un articolo, un libro, un tema scolastico e s\u00ec, anche una traduzione, in base a determinati criteri. Giornalisti, redattori, scrittori e traduttori temono e comunque guardano con diffidenza quello che invece gli studenti di scuola superiore potrebbero vedere come un nuovo alleato tra i banchi di scuola.<\/p>\n\n\n\n<p>Ma davvero noi traduttori e interpreti dobbiamo temere questo nuovo concorrente virtuale? S\u00ec, parlo anche per gli interpreti viste le nuove evoluzioni che si stanno testando anche sul piano verbale.<\/p>\n\n\n\n<p>Non pi\u00f9 del dovuto e vi spiego perch\u00e9.<\/p>\n\n\n\n<p>Vediamo prima in sintesi che cos\u2019\u00e8 la traduzione automatica o anche detta machine translation.<\/p>\n\n\n\n<p>La traduzione sfrutta l&#8217;intelligenza artificiale per tradurre automaticamente un testo da una lingua all&#8217;altra senza il coinvolgimento umano. La moderna traduzione automatica va oltre la semplice traduzione parola per parola per comunicare il pieno significato del testo in lingua originale nella lingua di destinazione. Analizza tutti gli elementi del testo e riconosce come le parole si influenzano a vicenda. Google Translate o meglio ancora DeepL sono due dei principali strumenti di traduzione automatica pi\u00f9 diffusi tra i gli addetti ai lavori e non solo. DeepL, ad esempio, \u00e8&nbsp;un servizio di traduzione gratuito multilingue, alimentato dalla&nbsp;<a href=\"https:\/\/it.wikipedia.org\/wiki\/Base_di_conoscenza\">base di conoscenza<\/a>&nbsp;di&nbsp;<a href=\"https:\/\/it.wikipedia.org\/wiki\/Linguee\">Linguee<\/a>, servizio creato dalla stessa azienda, DeepL GmbH (in precedenza chiamata Linguee). Il portale supporta 24 lingue per un totale di 552 combinazioni linguistiche.<\/p>\n\n\n\n<p>Lo scopo di quest\u2019articolo non \u00e8 quello di parlare dell\u2019arcinota traduzione automatica e di come questa si sia integrata nella prassi quotidiana dei traduttori e delle agenzie tramite i servizi di MTPE ovvero Machine Translation Post-Editing. Lo scopo di quest\u2019articolo \u00e8 di far capire quanto sia importante affidare il lato emotivo di un testo a un traduttore umano.<\/p>\n\n\n\n<p>Recentemente ho letto l\u2019interessantissimo saggio dello psicologo statunitense Daniel Goleman dal titolo \u201cIntelligenza emotiva \u2013 che cos\u2019\u00e8 e perch\u00e9 pu\u00f2 renderci felici\u201d. Il libro \u00e8 prevalentemente incentrato sulla gestione delle emozioni dal punto di visto sociale e soprattutto educativo. Ci spiega come funziona il nostro cervello quando ci troviamo a dover affrontare un\u2019emozione e soprattutto come possiamo gestirle nel miglior modo possibile. Indirettamente questo testo mi ha fatto molto riflettere non solo dal punto di vista umano ma anche professionale.<\/p>\n\n\n\n<p>Stiamo andando sempre pi\u00f9 verso un futuro disumanizzato in cui molti aspetti della nostra vita vengono demandati alle nuove tecnologie o pi\u00f9 propriamente alle macchine. Tutto questo ci porta a un grande analfabetismo emozionale ed anche il nostro lato professionale ne risente.<\/p>\n\n\n\n<p>\u00c8 vero. Abbiamo insegnato alle macchine molte cose, al punto che in termini di tempo riescono a svolgerle meglio di noi. Sono un ottimo supporto e possiamo anche dire che ci facilitano molto la vita. Ma davvero possiamo affidare tutto il nostro lato emozionale alle macchine?<\/p>\n\n\n\n<p>Provate a chiedere a Chat GPT di tradurre un testo particolarmente creativo in cui ogni sfumatura va a risvegliare una parte dei nostri sensi. Molto spesso le emozioni giocano con le parole e pu\u00f2 essere vero anche il contrario. Davvero la macchina pu\u00f2 farci provare le stesse emozioni?<\/p>\n\n\n\n<p>Tornando a Goleman che ci mette in guarda sull\u2019analfabetismo emozionale, perch\u00e9 non ritrovare quello che ci rende davvero umani nelle parole che scriviamo e che pronunciamo? Mi dispiace per il traduttore automatico, ma non potr\u00e0 mai apprendere da noi come funziona il nostro cuore.<\/p>\n\n\n\n<p>Caro cliente, se vuoi traduzioni che pensano e in cui vuoi sentire il cuore battere, pu\u00f2 aiutarti soltanto un traduttore umano. Quindi, chi avr\u00e0 la meglio nell\u2019eterna lotta tra un traduttore automatico e un traduttore in carne ed ossa? Vince chi emoziona, ma soprattutto chi sa farti emozionare. Non lasciare che la parte pi\u00f9 importante di te venga lasciata alle macchine. Il tuo messaggio scritto (e orale) ha bisogno di una voce che pensi e che sappia emozionare. La scelta sta a te\u2026 &nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a id=\"_ftn1\" href=\"#_ftnref1\">[1]<\/a> <a href=\"https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/#Cos8217e_ChatGPT\">https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/#Cos8217e_ChatGPT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019intelligenza artificiale sta rivoluzionando il mondo del lavoro e non in ultimo anche le professioni intellettuali, quelle in cui il cervello umano si esprime al meglio, si sentono minacciate dagli enormi passi in avanti che questa nuova frontiera dell\u2019innovazione tecnologica sta compiendo. Oggi si parla molto della nuova applicazione Chat GPT. Vediamo in sintesi di cosa si tratta e perch\u00e9 lo sviluppo di questa nuova tecnologia pu\u00f2 minacciare la figura del traduttore. Chat GPT&nbsp;\u00e8 il nuovo modello sviluppato da Open AI e fa parte dei&nbsp;modelli GPT-3&nbsp;(Generative Pre-trained Transformer 3). Sono modelli di intelligenza artificiale basati sul&nbsp;machine learning&nbsp;non supervisionato. Funzionano utilizzando una tecnica di&nbsp;deep learning&nbsp;nota come&nbsp;transformer, che consiste nell\u2019utilizzare una&nbsp;rete neurale&nbsp;per analizzare e comprendere il significato di un testo. Chat GPT&nbsp;nello specifico fa parte della famiglia degli&nbsp;Instruct GPT,&nbsp;quindi&nbsp;modelli&nbsp;formati tramite deep learning ma poi ottimizzati tramite il&nbsp;rinforzo umano, ovvero una tecnica nota come&nbsp;RLHF&nbsp;\u2013 Reinforcement Learning From&nbsp;Human&nbsp;Feedback. Chat GPT&nbsp;\u00e8 stato realizzato e reso pubblico a novembre del 2022. Grazie alla sua potenza e alla sua facilit\u00e0 d\u2019utilizzo sta spopolando sul web e molti, vista anche la possibilit\u00e0 di accedervi&nbsp;gratuitamente, ne stanno scoprendo le potenzialit\u00e0[1]. Chat GPT rende l\u2019interazione con l\u2019intelligenza artificiale pi\u00f9 naturale e intuitiva. Realizzato per ottimizzare la conversazione e facilitare l\u2019utilizzo da parte degli utenti,&nbsp;Chat GPT&nbsp;\u00e8 stato creato per aiutare gli utenti a interagire in modo pi\u00f9 semplice e fluido con&nbsp;GPT-3.&nbsp;Con&nbsp;Chat GPT&nbsp;\u00e8 possibile accedere gratuitamente, basta iscriversi con il proprio account Google o Microsoft.&nbsp; In sintesi, possiamo chiedere a Chat GPT di redigere un testo, un articolo, un libro, un tema scolastico e s\u00ec, anche una traduzione, in base a determinati criteri. Giornalisti, redattori, scrittori e traduttori temono e comunque guardano con diffidenza quello che invece gli studenti di scuola superiore potrebbero vedere come un nuovo alleato tra i banchi di scuola. Ma davvero noi traduttori e interpreti dobbiamo temere questo nuovo concorrente virtuale? S\u00ec, parlo anche per gli interpreti viste le nuove evoluzioni che si stanno testando anche sul piano verbale. Non pi\u00f9 del dovuto e vi spiego perch\u00e9. Vediamo prima in sintesi che cos\u2019\u00e8 la traduzione automatica o anche detta machine translation. La traduzione sfrutta l&#8217;intelligenza artificiale per tradurre automaticamente un testo da una lingua all&#8217;altra senza il coinvolgimento umano. La moderna traduzione automatica va oltre la semplice traduzione parola per parola per comunicare il pieno significato del testo in lingua originale nella lingua di destinazione. Analizza tutti gli elementi del testo e riconosce come le parole si influenzano a vicenda. Google Translate o meglio ancora DeepL sono due dei principali strumenti di traduzione automatica pi\u00f9 diffusi tra i gli addetti ai lavori e non solo. DeepL, ad esempio, \u00e8&nbsp;un servizio di traduzione gratuito multilingue, alimentato dalla&nbsp;base di conoscenza&nbsp;di&nbsp;Linguee, servizio creato dalla stessa azienda, DeepL GmbH (in precedenza chiamata Linguee). Il portale supporta 24 lingue per un totale di 552 combinazioni linguistiche. Lo scopo di quest\u2019articolo non \u00e8 quello di parlare dell\u2019arcinota traduzione automatica e di come questa si sia integrata nella prassi quotidiana dei traduttori e delle agenzie tramite i servizi di MTPE ovvero Machine Translation Post-Editing. Lo scopo di quest\u2019articolo \u00e8 di far capire quanto sia importante affidare il lato emotivo di un testo a un traduttore umano. Recentemente ho letto l\u2019interessantissimo saggio dello psicologo statunitense Daniel Goleman dal titolo \u201cIntelligenza emotiva \u2013 che cos\u2019\u00e8 e perch\u00e9 pu\u00f2 renderci felici\u201d. Il libro \u00e8 prevalentemente incentrato sulla gestione delle emozioni dal punto di visto sociale e soprattutto educativo. Ci spiega come funziona il nostro cervello quando ci troviamo a dover affrontare un\u2019emozione e soprattutto come possiamo gestirle nel miglior modo possibile. Indirettamente questo testo mi ha fatto molto riflettere non solo dal punto di vista umano ma anche professionale. Stiamo andando sempre pi\u00f9 verso un futuro disumanizzato in cui molti aspetti della nostra vita vengono demandati alle nuove tecnologie o pi\u00f9 propriamente alle macchine. Tutto questo ci porta a un grande analfabetismo emozionale ed anche il nostro lato professionale ne risente. \u00c8 vero. Abbiamo insegnato alle macchine molte cose, al punto che in termini di tempo riescono a svolgerle meglio di noi. Sono un ottimo supporto e possiamo anche dire che ci facilitano molto la vita. Ma davvero possiamo affidare tutto il nostro lato emozionale alle macchine? Provate a chiedere a Chat GPT di tradurre un testo particolarmente creativo in cui ogni sfumatura va a risvegliare una parte dei nostri sensi. Molto spesso le emozioni giocano con le parole e pu\u00f2 essere vero anche il contrario. Davvero la macchina pu\u00f2 farci provare le stesse emozioni? Tornando a Goleman che ci mette in guarda sull\u2019analfabetismo emozionale, perch\u00e9 non ritrovare quello che ci rende davvero umani nelle parole che scriviamo e che pronunciamo? Mi dispiace per il traduttore automatico, ma non potr\u00e0 mai apprendere da noi come funziona il nostro cuore. Caro cliente, se vuoi traduzioni che pensano e in cui vuoi sentire il cuore battere, pu\u00f2 aiutarti soltanto un traduttore umano. Quindi, chi avr\u00e0 la meglio nell\u2019eterna lotta tra un traduttore automatico e un traduttore in carne ed ossa? Vince chi emoziona, ma soprattutto chi sa farti emozionare. Non lasciare che la parte pi\u00f9 importante di te venga lasciata alle macchine. Il tuo messaggio scritto (e orale) ha bisogno di una voce che pensi e che sappia emozionare. La scelta sta a te\u2026 &nbsp; [1] https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/#Cos8217e_ChatGPT","protected":false},"author":1,"featured_media":5945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris\" \/>\n<meta property=\"og:description\" content=\"L\u2019intelligenza artificiale sta rivoluzionando il mondo del lavoro e non in ultimo anche le professioni intellettuali, quelle in cui il cervello umano si esprime al meglio, si sentono minacciate dagli enormi passi in avanti che questa nuova frontiera dell\u2019innovazione tecnologica sta compiendo. Oggi si parla molto della nuova applicazione Chat GPT. Vediamo in sintesi di cosa si tratta e perch\u00e9 lo sviluppo di questa nuova tecnologia pu\u00f2 minacciare la figura del traduttore. Chat GPT&nbsp;\u00e8 il nuovo modello sviluppato da Open AI e fa parte dei&nbsp;modelli GPT-3&nbsp;(Generative Pre-trained Transformer 3). Sono modelli di intelligenza artificiale basati sul&nbsp;machine learning&nbsp;non supervisionato. Funzionano utilizzando una tecnica di&nbsp;deep learning&nbsp;nota come&nbsp;transformer, che consiste nell\u2019utilizzare una&nbsp;rete neurale&nbsp;per analizzare e comprendere il significato di un testo. Chat GPT&nbsp;nello specifico fa parte della famiglia degli&nbsp;Instruct GPT,&nbsp;quindi&nbsp;modelli&nbsp;formati tramite deep learning ma poi ottimizzati tramite il&nbsp;rinforzo umano, ovvero una tecnica nota come&nbsp;RLHF&nbsp;\u2013 Reinforcement Learning From&nbsp;Human&nbsp;Feedback. Chat GPT&nbsp;\u00e8 stato realizzato e reso pubblico a novembre del 2022. Grazie alla sua potenza e alla sua facilit\u00e0 d\u2019utilizzo sta spopolando sul web e molti, vista anche la possibilit\u00e0 di accedervi&nbsp;gratuitamente, ne stanno scoprendo le potenzialit\u00e0[1]. Chat GPT rende l\u2019interazione con l\u2019intelligenza artificiale pi\u00f9 naturale e intuitiva. Realizzato per ottimizzare la conversazione e facilitare l\u2019utilizzo da parte degli utenti,&nbsp;Chat GPT&nbsp;\u00e8 stato creato per aiutare gli utenti a interagire in modo pi\u00f9 semplice e fluido con&nbsp;GPT-3.&nbsp;Con&nbsp;Chat GPT&nbsp;\u00e8 possibile accedere gratuitamente, basta iscriversi con il proprio account Google o Microsoft.&nbsp; In sintesi, possiamo chiedere a Chat GPT di redigere un testo, un articolo, un libro, un tema scolastico e s\u00ec, anche una traduzione, in base a determinati criteri. Giornalisti, redattori, scrittori e traduttori temono e comunque guardano con diffidenza quello che invece gli studenti di scuola superiore potrebbero vedere come un nuovo alleato tra i banchi di scuola. Ma davvero noi traduttori e interpreti dobbiamo temere questo nuovo concorrente virtuale? S\u00ec, parlo anche per gli interpreti viste le nuove evoluzioni che si stanno testando anche sul piano verbale. Non pi\u00f9 del dovuto e vi spiego perch\u00e9. Vediamo prima in sintesi che cos\u2019\u00e8 la traduzione automatica o anche detta machine translation. La traduzione sfrutta l&#8217;intelligenza artificiale per tradurre automaticamente un testo da una lingua all&#8217;altra senza il coinvolgimento umano. La moderna traduzione automatica va oltre la semplice traduzione parola per parola per comunicare il pieno significato del testo in lingua originale nella lingua di destinazione. Analizza tutti gli elementi del testo e riconosce come le parole si influenzano a vicenda. Google Translate o meglio ancora DeepL sono due dei principali strumenti di traduzione automatica pi\u00f9 diffusi tra i gli addetti ai lavori e non solo. DeepL, ad esempio, \u00e8&nbsp;un servizio di traduzione gratuito multilingue, alimentato dalla&nbsp;base di conoscenza&nbsp;di&nbsp;Linguee, servizio creato dalla stessa azienda, DeepL GmbH (in precedenza chiamata Linguee). Il portale supporta 24 lingue per un totale di 552 combinazioni linguistiche. Lo scopo di quest\u2019articolo non \u00e8 quello di parlare dell\u2019arcinota traduzione automatica e di come questa si sia integrata nella prassi quotidiana dei traduttori e delle agenzie tramite i servizi di MTPE ovvero Machine Translation Post-Editing. Lo scopo di quest\u2019articolo \u00e8 di far capire quanto sia importante affidare il lato emotivo di un testo a un traduttore umano. Recentemente ho letto l\u2019interessantissimo saggio dello psicologo statunitense Daniel Goleman dal titolo \u201cIntelligenza emotiva \u2013 che cos\u2019\u00e8 e perch\u00e9 pu\u00f2 renderci felici\u201d. Il libro \u00e8 prevalentemente incentrato sulla gestione delle emozioni dal punto di visto sociale e soprattutto educativo. Ci spiega come funziona il nostro cervello quando ci troviamo a dover affrontare un\u2019emozione e soprattutto come possiamo gestirle nel miglior modo possibile. Indirettamente questo testo mi ha fatto molto riflettere non solo dal punto di vista umano ma anche professionale. Stiamo andando sempre pi\u00f9 verso un futuro disumanizzato in cui molti aspetti della nostra vita vengono demandati alle nuove tecnologie o pi\u00f9 propriamente alle macchine. Tutto questo ci porta a un grande analfabetismo emozionale ed anche il nostro lato professionale ne risente. \u00c8 vero. Abbiamo insegnato alle macchine molte cose, al punto che in termini di tempo riescono a svolgerle meglio di noi. Sono un ottimo supporto e possiamo anche dire che ci facilitano molto la vita. Ma davvero possiamo affidare tutto il nostro lato emozionale alle macchine? Provate a chiedere a Chat GPT di tradurre un testo particolarmente creativo in cui ogni sfumatura va a risvegliare una parte dei nostri sensi. Molto spesso le emozioni giocano con le parole e pu\u00f2 essere vero anche il contrario. Davvero la macchina pu\u00f2 farci provare le stesse emozioni? Tornando a Goleman che ci mette in guarda sull\u2019analfabetismo emozionale, perch\u00e9 non ritrovare quello che ci rende davvero umani nelle parole che scriviamo e che pronunciamo? Mi dispiace per il traduttore automatico, ma non potr\u00e0 mai apprendere da noi come funziona il nostro cuore. Caro cliente, se vuoi traduzioni che pensano e in cui vuoi sentire il cuore battere, pu\u00f2 aiutarti soltanto un traduttore umano. Quindi, chi avr\u00e0 la meglio nell\u2019eterna lotta tra un traduttore automatico e un traduttore in carne ed ossa? Vince chi emoziona, ma soprattutto chi sa farti emozionare. Non lasciare che la parte pi\u00f9 importante di te venga lasciata alle macchine. Il tuo messaggio scritto (e orale) ha bisogno di una voce che pensi e che sappia emozionare. La scelta sta a te\u2026 &nbsp; [1] https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/#Cos8217e_ChatGPT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Paris\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T10:52:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-13T16:52:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sergioparis.it\/wp-content\/uploads\/2023\/03\/Immagine-articolo-23_3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"785\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sergio Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Paris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/\",\"url\":\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/\",\"name\":\"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris\",\"isPartOf\":{\"@id\":\"https:\/\/www.sergioparis.it\/#website\"},\"datePublished\":\"2023-03-10T10:52:10+00:00\",\"dateModified\":\"2023-06-13T16:52:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.sergioparis.it\/#\/schema\/person\/208882325827ec8accf4dfad6b86ed01\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sergioparis.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sergioparis.it\/#website\",\"url\":\"https:\/\/www.sergioparis.it\/\",\"name\":\"Sergio Paris\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sergioparis.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sergioparis.it\/#\/schema\/person\/208882325827ec8accf4dfad6b86ed01\",\"name\":\"Sergio Paris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.sergioparis.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/812b9900426c9e971e9ea2561bc0096a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/812b9900426c9e971e9ea2561bc0096a?s=96&d=mm&r=g\",\"caption\":\"Sergio Paris\"},\"url\":\"https:\/\/www.sergioparis.it\/de\/author\/wftuser\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris","og_description":"L\u2019intelligenza artificiale sta rivoluzionando il mondo del lavoro e non in ultimo anche le professioni intellettuali, quelle in cui il cervello umano si esprime al meglio, si sentono minacciate dagli enormi passi in avanti che questa nuova frontiera dell\u2019innovazione tecnologica sta compiendo. Oggi si parla molto della nuova applicazione Chat GPT. Vediamo in sintesi di cosa si tratta e perch\u00e9 lo sviluppo di questa nuova tecnologia pu\u00f2 minacciare la figura del traduttore. Chat GPT&nbsp;\u00e8 il nuovo modello sviluppato da Open AI e fa parte dei&nbsp;modelli GPT-3&nbsp;(Generative Pre-trained Transformer 3). Sono modelli di intelligenza artificiale basati sul&nbsp;machine learning&nbsp;non supervisionato. Funzionano utilizzando una tecnica di&nbsp;deep learning&nbsp;nota come&nbsp;transformer, che consiste nell\u2019utilizzare una&nbsp;rete neurale&nbsp;per analizzare e comprendere il significato di un testo. Chat GPT&nbsp;nello specifico fa parte della famiglia degli&nbsp;Instruct GPT,&nbsp;quindi&nbsp;modelli&nbsp;formati tramite deep learning ma poi ottimizzati tramite il&nbsp;rinforzo umano, ovvero una tecnica nota come&nbsp;RLHF&nbsp;\u2013 Reinforcement Learning From&nbsp;Human&nbsp;Feedback. Chat GPT&nbsp;\u00e8 stato realizzato e reso pubblico a novembre del 2022. Grazie alla sua potenza e alla sua facilit\u00e0 d\u2019utilizzo sta spopolando sul web e molti, vista anche la possibilit\u00e0 di accedervi&nbsp;gratuitamente, ne stanno scoprendo le potenzialit\u00e0[1]. Chat GPT rende l\u2019interazione con l\u2019intelligenza artificiale pi\u00f9 naturale e intuitiva. Realizzato per ottimizzare la conversazione e facilitare l\u2019utilizzo da parte degli utenti,&nbsp;Chat GPT&nbsp;\u00e8 stato creato per aiutare gli utenti a interagire in modo pi\u00f9 semplice e fluido con&nbsp;GPT-3.&nbsp;Con&nbsp;Chat GPT&nbsp;\u00e8 possibile accedere gratuitamente, basta iscriversi con il proprio account Google o Microsoft.&nbsp; In sintesi, possiamo chiedere a Chat GPT di redigere un testo, un articolo, un libro, un tema scolastico e s\u00ec, anche una traduzione, in base a determinati criteri. Giornalisti, redattori, scrittori e traduttori temono e comunque guardano con diffidenza quello che invece gli studenti di scuola superiore potrebbero vedere come un nuovo alleato tra i banchi di scuola. Ma davvero noi traduttori e interpreti dobbiamo temere questo nuovo concorrente virtuale? S\u00ec, parlo anche per gli interpreti viste le nuove evoluzioni che si stanno testando anche sul piano verbale. Non pi\u00f9 del dovuto e vi spiego perch\u00e9. Vediamo prima in sintesi che cos\u2019\u00e8 la traduzione automatica o anche detta machine translation. La traduzione sfrutta l&#8217;intelligenza artificiale per tradurre automaticamente un testo da una lingua all&#8217;altra senza il coinvolgimento umano. La moderna traduzione automatica va oltre la semplice traduzione parola per parola per comunicare il pieno significato del testo in lingua originale nella lingua di destinazione. Analizza tutti gli elementi del testo e riconosce come le parole si influenzano a vicenda. Google Translate o meglio ancora DeepL sono due dei principali strumenti di traduzione automatica pi\u00f9 diffusi tra i gli addetti ai lavori e non solo. DeepL, ad esempio, \u00e8&nbsp;un servizio di traduzione gratuito multilingue, alimentato dalla&nbsp;base di conoscenza&nbsp;di&nbsp;Linguee, servizio creato dalla stessa azienda, DeepL GmbH (in precedenza chiamata Linguee). Il portale supporta 24 lingue per un totale di 552 combinazioni linguistiche. Lo scopo di quest\u2019articolo non \u00e8 quello di parlare dell\u2019arcinota traduzione automatica e di come questa si sia integrata nella prassi quotidiana dei traduttori e delle agenzie tramite i servizi di MTPE ovvero Machine Translation Post-Editing. Lo scopo di quest\u2019articolo \u00e8 di far capire quanto sia importante affidare il lato emotivo di un testo a un traduttore umano. Recentemente ho letto l\u2019interessantissimo saggio dello psicologo statunitense Daniel Goleman dal titolo \u201cIntelligenza emotiva \u2013 che cos\u2019\u00e8 e perch\u00e9 pu\u00f2 renderci felici\u201d. Il libro \u00e8 prevalentemente incentrato sulla gestione delle emozioni dal punto di visto sociale e soprattutto educativo. Ci spiega come funziona il nostro cervello quando ci troviamo a dover affrontare un\u2019emozione e soprattutto come possiamo gestirle nel miglior modo possibile. Indirettamente questo testo mi ha fatto molto riflettere non solo dal punto di vista umano ma anche professionale. Stiamo andando sempre pi\u00f9 verso un futuro disumanizzato in cui molti aspetti della nostra vita vengono demandati alle nuove tecnologie o pi\u00f9 propriamente alle macchine. Tutto questo ci porta a un grande analfabetismo emozionale ed anche il nostro lato professionale ne risente. \u00c8 vero. Abbiamo insegnato alle macchine molte cose, al punto che in termini di tempo riescono a svolgerle meglio di noi. Sono un ottimo supporto e possiamo anche dire che ci facilitano molto la vita. Ma davvero possiamo affidare tutto il nostro lato emozionale alle macchine? Provate a chiedere a Chat GPT di tradurre un testo particolarmente creativo in cui ogni sfumatura va a risvegliare una parte dei nostri sensi. Molto spesso le emozioni giocano con le parole e pu\u00f2 essere vero anche il contrario. Davvero la macchina pu\u00f2 farci provare le stesse emozioni? Tornando a Goleman che ci mette in guarda sull\u2019analfabetismo emozionale, perch\u00e9 non ritrovare quello che ci rende davvero umani nelle parole che scriviamo e che pronunciamo? Mi dispiace per il traduttore automatico, ma non potr\u00e0 mai apprendere da noi come funziona il nostro cuore. Caro cliente, se vuoi traduzioni che pensano e in cui vuoi sentire il cuore battere, pu\u00f2 aiutarti soltanto un traduttore umano. Quindi, chi avr\u00e0 la meglio nell\u2019eterna lotta tra un traduttore automatico e un traduttore in carne ed ossa? Vince chi emoziona, ma soprattutto chi sa farti emozionare. Non lasciare che la parte pi\u00f9 importante di te venga lasciata alle macchine. Il tuo messaggio scritto (e orale) ha bisogno di una voce che pensi e che sappia emozionare. La scelta sta a te\u2026 &nbsp; [1] https:\/\/smartstrategy.eu\/intelligenza-artificiale\/chat-gpt-3-come-accedere-e-testare-il-nuovo-modello-di-gpt-3\/#Cos8217e_ChatGPT","og_url":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/","og_site_name":"Sergio Paris","article_published_time":"2023-03-10T10:52:10+00:00","article_modified_time":"2023-06-13T16:52:32+00:00","og_image":[{"width":785,"height":469,"url":"https:\/\/www.sergioparis.it\/wp-content\/uploads\/2023\/03\/Immagine-articolo-23_3.png","type":"image\/png"}],"author":"Sergio Paris","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sergio Paris","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/","url":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/","name":"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9 - Sergio Paris","isPartOf":{"@id":"https:\/\/www.sergioparis.it\/#website"},"datePublished":"2023-03-10T10:52:10+00:00","dateModified":"2023-06-13T16:52:32+00:00","author":{"@id":"https:\/\/www.sergioparis.it\/#\/schema\/person\/208882325827ec8accf4dfad6b86ed01"},"breadcrumb":{"@id":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sergioparis.it\/de\/traduttore-umano-vs-traduttore-automatico-vince-chi-emoziona-di-piu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sergioparis.it\/de\/"},{"@type":"ListItem","position":2,"name":"TRADUTTORE UMANO VS TRADUTTORE AUTOMATICO \u2013 VINCE CHI EMOZIONA DI PI\u00d9"}]},{"@type":"WebSite","@id":"https:\/\/www.sergioparis.it\/#website","url":"https:\/\/www.sergioparis.it\/","name":"Sergio Paris","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sergioparis.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.sergioparis.it\/#\/schema\/person\/208882325827ec8accf4dfad6b86ed01","name":"Sergio Paris","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sergioparis.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/812b9900426c9e971e9ea2561bc0096a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/812b9900426c9e971e9ea2561bc0096a?s=96&d=mm&r=g","caption":"Sergio Paris"},"url":"https:\/\/www.sergioparis.it\/de\/author\/wftuser\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/posts\/5948"}],"collection":[{"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/comments?post=5948"}],"version-history":[{"count":3,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/posts\/5948\/revisions"}],"predecessor-version":[{"id":5956,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/posts\/5948\/revisions\/5956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/media\/5945"}],"wp:attachment":[{"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/media?parent=5948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/categories?post=5948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sergioparis.it\/de\/wp-json\/wp\/v2\/tags?post=5948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}